{"id":15628,"date":"2019-03-05T18:40:37","date_gmt":"2019-03-05T23:40:37","guid":{"rendered":"http:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg"},"modified":"2019-03-07T12:35:20","modified_gmt":"2019-03-07T17:35:20","slug":"palta-cardenal07-2","status":"inherit","type":"attachment","link":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/","title":{"rendered":"Palta-cardenal07"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"class_list":{"0":"post-15628","1":"attachment","2":"type-attachment","3":"status-inherit","5":"entry","6":"has-post-thumbnail"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Palta-cardenal07 &#8211; Mi Diario de Cocina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palta-cardenal07 &#8211; Mi Diario de Cocina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mi Diario de Cocina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/midiariodecocina\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-07T17:35:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Mooncarolina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/\",\"url\":\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/\",\"name\":\"Palta-cardenal07 &#8211; Mi Diario de Cocina\",\"isPartOf\":{\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/#website\"},\"datePublished\":\"2019-03-05T23:40:37+00:00\",\"dateModified\":\"2019-03-07T17:35:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.midiariodecocina.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cardinal Stuffed Avocado\",\"item\":\"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Palta-cardenal07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/#website\",\"url\":\"https:\/\/www.midiariodecocina.com\/en\/\",\"name\":\"Mi Diario de Cocina\",\"description\":\"F\u00e1ciles y deliciosas recetas de cocina\",\"publisher\":{\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.midiariodecocina.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/#organization\",\"name\":\"Mi Diario de Cocina\",\"url\":\"https:\/\/www.midiariodecocina.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/04\/cropped-MDDC_Favicon_color_512x512.png\",\"contentUrl\":\"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/04\/cropped-MDDC_Favicon_color_512x512.png\",\"width\":512,\"height\":512,\"caption\":\"Mi Diario de Cocina\"},\"image\":{\"@id\":\"https:\/\/www.midiariodecocina.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/midiariodecocina\",\"https:\/\/x.com\/Mooncarolina\",\"http:\/\/instagram.com\/midiariodecocina\",\"http:\/\/www.pinterest.com\/mooncarolina\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palta-cardenal07 &#8211; Mi Diario de Cocina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/","og_locale":"en_US","og_type":"article","og_title":"Palta-cardenal07 &#8211; Mi Diario de Cocina","og_url":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/","og_site_name":"Mi Diario de Cocina","article_publisher":"https:\/\/www.facebook.com\/midiariodecocina","article_modified_time":"2019-03-07T17:35:20+00:00","og_image":[{"width":700,"height":1050,"url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Mooncarolina","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/","url":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/","name":"Palta-cardenal07 &#8211; Mi Diario de Cocina","isPartOf":{"@id":"https:\/\/www.midiariodecocina.com\/en\/#website"},"datePublished":"2019-03-05T23:40:37+00:00","dateModified":"2019-03-07T17:35:20+00:00","breadcrumb":{"@id":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/palta-cardenal07-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.midiariodecocina.com\/en\/"},{"@type":"ListItem","position":2,"name":"Cardinal Stuffed Avocado","item":"https:\/\/www.midiariodecocina.com\/en\/cardinal-stuffed-avocado\/"},{"@type":"ListItem","position":3,"name":"Palta-cardenal07"}]},{"@type":"WebSite","@id":"https:\/\/www.midiariodecocina.com\/en\/#website","url":"https:\/\/www.midiariodecocina.com\/en\/","name":"Mi Diario de Cocina","description":"F\u00e1ciles y deliciosas recetas de cocina","publisher":{"@id":"https:\/\/www.midiariodecocina.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.midiariodecocina.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.midiariodecocina.com\/en\/#organization","name":"Mi Diario de Cocina","url":"https:\/\/www.midiariodecocina.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.midiariodecocina.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/04\/cropped-MDDC_Favicon_color_512x512.png","contentUrl":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/04\/cropped-MDDC_Favicon_color_512x512.png","width":512,"height":512,"caption":"Mi Diario de Cocina"},"image":{"@id":"https:\/\/www.midiariodecocina.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/midiariodecocina","https:\/\/x.com\/Mooncarolina","http:\/\/instagram.com\/midiariodecocina","http:\/\/www.pinterest.com\/mooncarolina\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg'><img decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Palta cardenal\" srcset=\"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-200x300.jpg 200w, https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-683x1024.jpg 683w, https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg 700w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Palta cardenal","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":1050,"file":"2019\/03\/Palta-cardenal07.jpg","sizes":{"thumbnail":{"file":"Palta-cardenal07-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-150x150.jpg"},"medium":{"file":"Palta-cardenal07-200x300.jpg","width":200,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-200x300.jpg"},"large":{"file":"Palta-cardenal07-683x1024.jpg","width":683,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-683x1024.jpg"},"horizontal-thumbnail":{"file":"Palta-cardenal07-680x450.jpg","width":680,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-680x450.jpg"},"vertical-thumbnail":{"file":"Palta-cardenal07-680x900.jpg","width":680,"height":900,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-680x900.jpg"},"square-thumbnail":{"file":"Palta-cardenal07-320x320.jpg","width":320,"height":320,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-320x320.jpg"},"slider":{"file":"Palta-cardenal07-680x350.jpg","width":680,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-680x350.jpg"},"wp_rp_thumbnail":{"file":"Palta-cardenal07-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07-150x150.jpg"},"full":{"file":"Palta-cardenal07.jpg","width":700,"height":1050,"mime_type":"image\/jpeg","source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":15639,"source_url":"https:\/\/www.midiariodecocina.com\/wp-content\/uploads\/2019\/03\/Palta-cardenal07.jpg","_links":{"self":[{"href":"https:\/\/www.midiariodecocina.com\/en\/wp-json\/wp\/v2\/media\/15628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.midiariodecocina.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.midiariodecocina.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.midiariodecocina.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.midiariodecocina.com\/en\/wp-json\/wp\/v2\/comments?post=15628"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":15639,"href":"https:\/\/www.midiariodecocina.com\/en\/wp-json\/wp\/v2\/posts\/15639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}